{"id":2975,"date":"2024-07-16T21:30:34","date_gmt":"2024-07-16T21:30:34","guid":{"rendered":"https:\/\/bigfishinitiative.com\/?p=2975"},"modified":"2024-07-17T16:13:10","modified_gmt":"2024-07-17T16:13:10","slug":"habitats-esenciales-para-los-peces-espanol","status":"publish","type":"post","link":"https:\/\/bigfishinitiative.com\/fr\/material-type\/video\/2975\/habitats-esenciales-para-los-peces-espanol\/","title":{"rendered":"H\u00e1bitats Esenciales para los Peces (Espanol)"},"content":{"rendered":"<div id=\"fws_6a04f954bc6df\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row vc_row-o-full-height vc_row-o-columns-stretch vc_row-o-equal-height vc_row-flex vc_row-o-content-middle\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>S\u00e9ries \u00e9ducatives sur les habitats des animaux, comme les fondations Lodo et Arena, les estuaires, la colonne d'eau, l'arche de corail et un guide sur la consommation durable.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <a href=\"https:\/\/f.io\/Xl7b0GLi\" target=\"_self\" class=\"\">\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"1080\" width=\"1920\" data-animation=\"none\" src=\"https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_714.jpg\" alt=\"\" srcset=\"https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_714.jpg 1920w, https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_714-300x169.jpg 300w, https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_714-1024x576.jpg 1024w, https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_714-768x432.jpg 768w, https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_714-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\n            <\/a>\n          <\/div>\n        <\/div>\n      <\/div>\n      <\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div><a class=\"nectar-button large regular accent-color  regular-button\"  role=\"button\" style=\"\" target=\"_blank\" href=\"https:\/\/f.io\/Xl7b0GLi\" data-color-override=\"false\" data-hover-color-override=\"false\" data-hover-text-color-override=\"#fff\"><span>Voir la vid\u00e9o<\/span><\/a><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div><div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <a href=\"https:\/\/f.io\/FhbPFOZd\" target=\"_self\" class=\"\">\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"1080\" width=\"1920\" data-animation=\"none\" src=\"https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_744.jpg\" alt=\"\" srcset=\"https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_744.jpg 1920w, https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_744-300x169.jpg 300w, https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_744-1024x576.jpg 1024w, https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_744-768x432.jpg 768w, https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_744-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\n            <\/a>\n          <\/div>\n        <\/div>\n      <\/div>\n      <\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div><a class=\"nectar-button large regular accent-color  regular-button\"  role=\"button\" style=\"\" target=\"_blank\" href=\"https:\/\/f.io\/FhbPFOZd\" data-color-override=\"false\" data-hover-color-override=\"false\" data-hover-text-color-override=\"#fff\"><span>Voir la vid\u00e9o <\/span><\/a><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div><div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <a href=\"https:\/\/f.io\/nciD3Z1x\" target=\"_self\" class=\"\">\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"1080\" width=\"1920\" data-animation=\"none\" src=\"https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_679.jpg\" alt=\"\" srcset=\"https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_679.jpg 1920w, https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_679-300x169.jpg 300w, https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_679-1024x576.jpg 1024w, https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_679-768x432.jpg 768w, https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_679-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\n            <\/a>\n          <\/div>\n        <\/div>\n      <\/div>\n      <\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div><a class=\"nectar-button large regular accent-color  regular-button\"  role=\"button\" style=\"\" target=\"_blank\" href=\"https:\/\/f.io\/nciD3Z1x\" data-color-override=\"false\" data-hover-color-override=\"false\" data-hover-text-color-override=\"#fff\"><span>Voir la vid\u00e9o<\/span><\/a><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div><div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <a href=\"https:\/\/f.io\/V7E3X3D6\" target=\"_self\" class=\"\">\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"1080\" width=\"1920\" data-animation=\"none\" src=\"https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_726.jpg\" alt=\"\" srcset=\"https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_726.jpg 1920w, https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_726-300x169.jpg 300w, https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_726-1024x576.jpg 1024w, https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_726-768x432.jpg 768w, https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_726-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\n            <\/a>\n          <\/div>\n        <\/div>\n      <\/div>\n      <\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div><a class=\"nectar-button large regular accent-color  regular-button\"  role=\"button\" style=\"\" target=\"_blank\" href=\"https:\/\/f.io\/V7E3X3D6\" data-color-override=\"false\" data-hover-color-override=\"false\" data-hover-text-color-override=\"#fff\"><span>Voir la vid\u00e9o<\/span><\/a><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div><div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <a href=\"https:\/\/f.io\/v6CLbOrs\" target=\"_self\" class=\"\">\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"1080\" width=\"1920\" data-animation=\"none\" src=\"https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_699.jpg\" alt=\"\" srcset=\"https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_699.jpg 1920w, https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_699-300x169.jpg 300w, https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_699-1024x576.jpg 1024w, https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_699-768x432.jpg 768w, https:\/\/bigfishinitiative.com\/wp-content\/uploads\/2024\/07\/frame_699-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\n            <\/a>\n          <\/div>\n        <\/div>\n      <\/div>\n      <\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div><a class=\"nectar-button large regular accent-color  regular-button\"  role=\"button\" style=\"\" target=\"_blank\" href=\"https:\/\/f.io\/v6CLbOrs\" data-color-override=\"false\" data-hover-color-override=\"false\" data-hover-text-color-override=\"#fff\"><span>Voir la vid\u00e9o<\/span><\/a>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Series educativas sobre los h\u00e1bitats de los peces, como los Fondos Lodo y Arena, Estuarios, Columna de Agua, Arrecife de Coral y gu\u00eda sobre consumo sostenible. Ver V\u00eddeo Ver V\u00eddeo...","protected":false},"author":4,"featured_media":3040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"h5ap_radio_sources":[],"footnotes":""},"categories":[79,80,209,205,63,81,39,34,199],"tags":[],"class_list":{"0":"post-2975","1":"post","2":"type-post","3":"status-publish","4":"format-video","5":"has-post-thumbnail","7":"category-coral-reefs","8":"category-education","9":"category-food-web","10":"category-marine-protected-areas","11":"category-puerto-rico","12":"category-restoration","13":"category-spanish","14":"category-video","15":"category-wider-caribbean","16":"post_format-post-format-video"},"_links":{"self":[{"href":"https:\/\/bigfishinitiative.com\/fr\/wp-json\/wp\/v2\/posts\/2975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bigfishinitiative.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bigfishinitiative.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bigfishinitiative.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bigfishinitiative.com\/fr\/wp-json\/wp\/v2\/comments?post=2975"}],"version-history":[{"count":10,"href":"https:\/\/bigfishinitiative.com\/fr\/wp-json\/wp\/v2\/posts\/2975\/revisions"}],"predecessor-version":[{"id":2982,"href":"https:\/\/bigfishinitiative.com\/fr\/wp-json\/wp\/v2\/posts\/2975\/revisions\/2982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bigfishinitiative.com\/fr\/wp-json\/wp\/v2\/media\/3040"}],"wp:attachment":[{"href":"https:\/\/bigfishinitiative.com\/fr\/wp-json\/wp\/v2\/media?parent=2975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bigfishinitiative.com\/fr\/wp-json\/wp\/v2\/categories?post=2975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bigfishinitiative.com\/fr\/wp-json\/wp\/v2\/tags?post=2975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}